{"id":180,"date":"2019-03-14T13:24:54","date_gmt":"2019-03-14T12:24:54","guid":{"rendered":"http:\/\/blog.lactolerance.fr\/?p=180"},"modified":"2023-11-15T11:57:32","modified_gmt":"2023-11-15T10:57:32","slug":"poulet-marengo-sans-lactose","status":"publish","type":"post","link":"https:\/\/www.lactolerance.fr\/blog\/poulet-marengo-sans-lactose\/","title":{"rendered":"Poulet Marengo sans lactose"},"content":{"rendered":"\r\n<p>Une recette traditionnelle fran\u00e7aise, un plat mijot\u00e9 pour le plaisir de d\u00e9guster un poulet fondant et moelleux et sans lactose, \u00e9videmment !<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Ingr\u00e9dients<\/h2>\r\n\r\n\r\n\r\n<p>Pour 4 personnes :<\/p>\r\n\r\n\r\n\r\n<p>&#8211; 1 poulet en morceaux<br \/>&#8211; 400 g de concass\u00e9 de tomates<br \/>&#8211; 250 g de champignons de Paris<br \/>&#8211; 12 olives noires<br \/>&#8211; 1 c. \u00e0 soupe de concentr\u00e9 de tomates<br \/>&#8211; 25 cl de vin blanc sec<br \/>&#8211; 1 morceau de sucre<br \/>&#8211; 2 oignons, 3 gousses d\u2019ail, 1 bouquet garni<br \/>&#8211; Huile d\u2019olive, sel, poivre du moulin<br \/>&#8211; Persil hach\u00e9<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Pr\u00e9paration<\/h2>\r\n\r\n\r\n\r\n<p>Pr\u00e9paration\u00a0: 20 min \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0Cuisson\u00a0: 1h25<\/p>\r\n\r\n\r\n\r\n<p>1.\u00a0\u00a0 Peler et couper finement les oignons.<br \/>2.\u00a0\u00a0 Faire blanchir les olives 3 min. \u00e0 l\u2019eau bouillante, \u00e9goutter.<br \/>3.\u00a0\u00a0 Dans une grande casserole anti-adh\u00e9rente, faire dorer 15 min. les morceaux de poulet sur toutes les faces dans l\u2019huile d\u2019olive, puis les sortir et les garder au chaud.<br \/>4.\u00a0\u00a0 Dans la m\u00eame casserole, faire dorer les oignons 5 min. \u00e0 feu doux dans un peu d\u2019huile d\u2019olive.<br \/>5.\u00a0\u00a0 Ajouter le concass\u00e9 de tomates et l\u2019ail, m\u00e9langer et continuer la cuisson 5 min. \u00e0 feu moyen.<br \/>6.\u00a0\u00a0 Ajouter le concentr\u00e9 de tomates, le morceau de sucre et le bouquet garni. Saler, poivrer, m\u00e9langer et couvrir.<br \/>7.\u00a0\u00a0 Laisser mijoter 20 min \u00e0 feu doux.<br \/>8.\u00a0\u00a0 Nettoyer et \u00e9mincer les champignons. Les faire revenir 5 min. dans l\u2019huile d\u2019olive.<br \/>9.\u00a0\u00a0 Enlever le bouquet garni. Ajouter le poulet et les champignons dans la casserole. Couvrir et faire cuire encore 40 min. \u00e0 feu doux. Ajouter les olives et le persil.<br \/>10.\u00a0 Rectifier l\u2019assaisonnement.<\/p>\r\n<p><a href=\"https:\/\/www.lactolerance.fr\/fr\/nos-complements-alimentaires\/134-pack-decouverte-protection-24h-134.html\"><img decoding=\"async\" class=\"alignnone wp-image-1108 size-full\" src=\"https:\/\/www.lactolerance.fr\/blog\/wp-content\/uploads\/2022\/12\/Blog-bas-de-page-FR-NOUVEAU-PACK-Decouverte.jpg\" alt=\"Image redirigeant vers la fiche produit du pack lactor\u00e9lance 1day et le pilulier 9000\" width=\"100%\" height=\"NaN\" srcset=\"https:\/\/www.lactolerance.fr\/blog\/wp-content\/uploads\/2022\/12\/Blog-bas-de-page-FR-NOUVEAU-PACK-Decouverte.jpg 2400w, https:\/\/www.lactolerance.fr\/blog\/wp-content\/uploads\/2022\/12\/Blog-bas-de-page-FR-NOUVEAU-PACK-Decouverte-400x133.jpg 400w, https:\/\/www.lactolerance.fr\/blog\/wp-content\/uploads\/2022\/12\/Blog-bas-de-page-FR-NOUVEAU-PACK-Decouverte-800x267.jpg 800w, https:\/\/www.lactolerance.fr\/blog\/wp-content\/uploads\/2022\/12\/Blog-bas-de-page-FR-NOUVEAU-PACK-Decouverte-768x256.jpg 768w, https:\/\/www.lactolerance.fr\/blog\/wp-content\/uploads\/2022\/12\/Blog-bas-de-page-FR-NOUVEAU-PACK-Decouverte-1536x512.jpg 1536w, https:\/\/www.lactolerance.fr\/blog\/wp-content\/uploads\/2022\/12\/Blog-bas-de-page-FR-NOUVEAU-PACK-Decouverte-2048x683.jpg 2048w, https:\/\/www.lactolerance.fr\/blog\/wp-content\/uploads\/2022\/12\/Blog-bas-de-page-FR-NOUVEAU-PACK-Decouverte-18x6.jpg 18w\" sizes=\"(max-width: 2400px) 100vw, 2400px\" \/><\/a><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Une recette traditionnelle fran\u00e7aise, un plat mijot\u00e9 pour le plaisir de d\u00e9guster un poulet fondant et moelleux et sans lactose, \u00e9videmment ! Ingr\u00e9dients Pour 4 personnes : &#8211; 1 poulet en morceaux&#8211; 400 g de concass\u00e9 de tomates&#8211; 250 g de champignons de Paris&#8211; 12 olives noires&#8211; 1 c. \u00e0 soupe de concentr\u00e9 de tomates&#8211; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recettes-sans-lactose"],"_links":{"self":[{"href":"https:\/\/www.lactolerance.fr\/blog\/wp-json\/wp\/v2\/posts\/180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lactolerance.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lactolerance.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lactolerance.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lactolerance.fr\/blog\/wp-json\/wp\/v2\/comments?post=180"}],"version-history":[{"count":4,"href":"https:\/\/www.lactolerance.fr\/blog\/wp-json\/wp\/v2\/posts\/180\/revisions"}],"predecessor-version":[{"id":1732,"href":"https:\/\/www.lactolerance.fr\/blog\/wp-json\/wp\/v2\/posts\/180\/revisions\/1732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lactolerance.fr\/blog\/wp-json\/wp\/v2\/media\/181"}],"wp:attachment":[{"href":"https:\/\/www.lactolerance.fr\/blog\/wp-json\/wp\/v2\/media?parent=180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lactolerance.fr\/blog\/wp-json\/wp\/v2\/categories?post=180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lactolerance.fr\/blog\/wp-json\/wp\/v2\/tags?post=180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}